{"id":286343,"date":"2021-05-03T18:13:32","date_gmt":"2021-05-03T18:13:32","guid":{"rendered":"https:\/\/stage.veronneau.com\/?p=286343"},"modified":"2023-05-09T16:25:01","modified_gmt":"2023-05-09T16:25:01","slug":"comment-creer-une-ambiance-zen-interieur-exterieur","status":"publish","type":"post","link":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/","title":{"rendered":"Comment cr\u00e9er une ambiance zen, \u00e0 l&rsquo;int\u00e9rieur comme \u00e0 l&rsquo;ext\u00e9rieur ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"286343\" class=\"elementor elementor-286343\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6efb2c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6efb2c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-962b58b\" data-id=\"962b58b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4d6d77 elementor-widget elementor-widget-text-editor\" data-id=\"e4d6d77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Envie de d\u00e9crocher dans un lieu reposant ? Sachez qu\u2019il existe un moyen facile de vous ressourcer et de profiter pleinement des vacances d\u2019\u00e9t\u00e9 sans m\u00eame voyager ! En effet, rien de mieux que de ressentir l\u2019ambiance du voyage dans votre propre maison, gr\u00e2ce \u00e0 quelques am\u00e9liorations niveau d\u00e9coration. Continuez votre lecture pour d\u00e9couvrir 5 accessoires incontournables pour cr\u00e9er votre espace d\u00e9tente, au jardin comme \u00e0 l\u2019int\u00e9rieur de la maison, et ce, \u00e0 petit prix.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c5541c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c5541c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-298ddc5\" data-id=\"298ddc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76f38e8 elementor-widget elementor-widget-heading\" data-id=\"76f38e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00eates de bouddha<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b7618b elementor-widget elementor-widget-text-editor\" data-id=\"7b7618b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Saviez-vous que la <span style=\"text-decoration: underline;\"><a href=\"https:\/\/veronneau.com\/fr\/categorie-produit\/exterieur-jardin\/accessoires-de-jardin\/\">t\u00eate de bouddha<\/a><\/span> est \u00e0 nouveau une grande tendance en d\u00e9coration int\u00e9rieure et ext\u00e9rieure ? Aujourd\u2019hui, cet objet d\u00e9co &#8211; autrefois r\u00e9serv\u00e9 aux d\u00e9cors traditionnels &#8211; fait maintenant partie des d\u00e9cors les plus modernes. Combinez-le aux accessoires minimalistes comme les vases de verre, paniers boho et pots en terre cuite; le r\u00e9sultat sera des plus tendance !\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e573c36 elementor-widget elementor-widget-spacer\" data-id=\"e573c36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-480e3b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"480e3b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ddc44b6\" data-id=\"ddc44b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6709dbe elementor-widget elementor-widget-heading\" data-id=\"6709dbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lanternes et bougies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c677c8f elementor-widget elementor-widget-text-editor\" data-id=\"c677c8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un d\u00e9cor zen signifie d\u2019abord et avant tout un milieu reposant ! Ceci dit, il est pr\u00e9f\u00e9rable de choisir des lumi\u00e8res douces pour une atmosph\u00e8re relaxante. Lanternes, votives et bougies seront parfaites pour cr\u00e9er un \u00e9clairage tamis\u00e9. L\u2019avantage de ce genre d\u2019\u00e9clairage, c\u2019est qu&rsquo;il convient tant \u00e0 la terrasse qu\u2019\u00e0 l\u2019int\u00e9rieur de la maison. En effet, certaines chandelles fonctionnant au DEL sont \u00e0 l\u2019\u00e9preuve des intemp\u00e9ries, donc elles peuvent \u00eatre utilis\u00e9es pour l\u2019ext\u00e9rieur de la maison. C\u2019est le cas de <span style=\"text-decoration: underline;\"><a href=\"https:\/\/veronneau.com\/fr\/produits\/decor\/chandeliers-et-lanternes\/chandelle-rainlite-au-del-exterieur-moyen\/\">la gamme de bougies Rainlite<\/a><\/span> !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90717a6 elementor-widget elementor-widget-spacer\" data-id=\"90717a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a3cee3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a3cee3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bfc94a9\" data-id=\"bfc94a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d20099 elementor-widget elementor-widget-heading\" data-id=\"3d20099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Jet\u00e9s, coussins, foyers ; tout ce qui am\u00e8ne de la chaleur !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a59d384 elementor-widget elementor-widget-text-editor\" data-id=\"a59d384\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quand vient le moment de d\u00e9corer une pi\u00e8ce ou une terrasse au style zen, il est pr\u00e9f\u00e9rable d\u2019opter pour les couleurs neutres dans le choix de <span style=\"text-decoration: underline;\"><a href=\"https:\/\/veronneau.com\/fr\/categorie-produit\/exterieur-jardin\/accessoires-de-jardin\/\">vos d\u00e9corations<\/a><\/span>. Misez \u00e9galement sur les formes arrondies et les mati\u00e8res naturelles et confortables, \u00e0 la base du Feng Shui. Pensez au m\u00e9lange de textile avec un foyer couleur rouille &#8211; tr\u00e8s tendance &#8211; apportant un esprit cocooning. On peut \u00e9galement y accrocher un miroir rond qui donne une illusion de grandeur \u00e0 l\u2019espace. Imaginez vos soir\u00e9es d\u2019\u00e9t\u00e9 autour d\u2019un feu dans un d\u00e9cor chaleureux&#8230;un sentiment de paix in\u00e9gal\u00e9 !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35695d5 elementor-widget elementor-widget-spacer\" data-id=\"35695d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25cb247 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25cb247\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d83fb7\" data-id=\"8d83fb7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3739a33 elementor-widget elementor-widget-heading\" data-id=\"3739a33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Grenouilles d\u00e9coratives<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20ec933 elementor-widget elementor-widget-text-editor\" data-id=\"20ec933\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Symbole Feng Shui bien connu, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/veronneau.com\/fr\/categorie-produit\/exterieur-jardin\/accessoires-de-jardin\/\">le crapaud d\u00e9coratif<\/a><\/span> a plusieurs significations dans le monde spirituel : le renouveau, l\u2019abondance et m\u00eame la lib\u00e9ration. En d\u00e9coration, vous trouverez les figurines de grenouilles sous diverses formes telles que : mangeoires d\u2019oiseaux, statuettes, fontaines, etc. Notre suggestion : utilisez-les pour d\u00e9corer le jardin en les combinant avec des plantes vertes d\u2019ext\u00e9rieur et autres accessoires de jardin. Rapprochez-vous de la nature avec cette inspiration de d\u00e9cor ext\u00e9rieur !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1146da elementor-widget elementor-widget-spacer\" data-id=\"c1146da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad3a283 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad3a283\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d0b730\" data-id=\"0d0b730\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e30bca8 elementor-widget elementor-widget-heading\" data-id=\"e30bca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plantes vertes tropicales, bambous et bonsa\u00efs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecf663d elementor-widget elementor-widget-text-editor\" data-id=\"ecf663d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quel est le r\u00f4le des plantes dans un d\u00e9cor zen ? Non seulement, elles repr\u00e9sentent la nature, mais elles permettent aussi de s\u2019\u00e9vader dans un environnement vert luxuriant. Par exemple, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/veronneau.com\/fr\/categorie-produit\/plantes-artificielles\/interieur\/bonsais-artificiels\/\">le bonsa\u00ef<\/a><\/span>, un art japonais traditionnel des moines bouddhistes, sera un alli\u00e9 de choix ! Toutes les plantes au feuillage clairsem\u00e9 qui ne sont pas trop imposantes seront des accessoires d\u00e9co indispensables. Pensez au <span style=\"text-decoration: underline;\"><a href=\"https:\/\/veronneau.com\/fr\/produits\/plantes-artificielles\/interieur\/plantes-vertes-artificielles\/bambou-japonica-artificiel-48\/\">bambou artificiel<\/a><\/span>, une plante zen au premier regard !\u00a0<\/p><p>C\u00f4t\u00e9 jardin, optez pour des herbes vertes artificielles qui se plantent bien dans des bacs noirs. Non seulement elles ajouteront de la verdure, mais elles sauront cr\u00e9er une terrasse \u00e9voquant la nature. Laissez-vous transporter dans une ambiance calme et sereine !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3bb17c elementor-widget elementor-widget-spacer\" data-id=\"e3bb17c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6c0cd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6c0cd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11d6e95\" data-id=\"11d6e95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e36985f elementor-widget elementor-widget-heading\" data-id=\"e36985f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Magasinez les essentiels pour un d\u00e9cor zen:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2a8ef4 elementor-widget__width-initial elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"a2a8ef4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/veronneau.com\/fr\/produits\/plantes-artificielles\/interieur\/plantes-vertes-artificielles\/bambou-japonica-artificiel-48\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/veronneau.com\/wp-content\/uploads\/nc\/catalog\/acomba\/BAMBOU-JAPONICA-ARTIFICIEL-48-B107TBV.JPG&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/veronneau.com\/fr\/produits\/decor\/accessoires-decoratifs\/statue-bouddha-meditatif-en-polyresine-20-x-14\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/veronneau.com\/wp-content\/uploads\/nc\/catalog\/acomba\/STATUE-BOUDDHA-MEDITATIF-EN-POLYRESINE-20-X-14-114123.JPG&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/veronneau.com\/fr\/produits\/decor\/chandeliers-et-lanternes\/lanterne-solaire-en-metal-mat-8-x-45\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/veronneau.com\/wp-content\/uploads\/nc\/catalog\/acomba\/LANTERNE-SOLAIRE-EN-METAL-MAT-8-X-45-512000810.JPG&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/veronneau.com\/fr\/produits\/exterieur-jardin\/thematiques-jardin\/les-essentiels-du-style-zen\/herbes-de-graminee-artificielle-en-pot-exterieur-41\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/veronneau.com\/wp-content\/uploads\/nc\/catalog\/acomba\/HERBES-DE-GRAMINEE-ARTIFICIELLE-EN-POT-EXTERIEUR-41-101003944.JPG&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/veronneau.com\/fr\/produits\/exterieur-jardin\/thematiques-jardin\/les-essentiels-du-style-zen\/herbes-de-riviere-artificielles-dexterieur-58\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/veronneau.com\/wp-content\/uploads\/nc\/catalog\/acomba\/HERBES-DE-RIVIERE-EN-POT-INTEXT-58-101003509.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"text-align: justify;\">\n\tEnvie de d&eacute;crocher dans un lieu reposant ? Sachez qu&rsquo;il existe un moyen facile de vous ressourcer et de profiter pleinement des vacances d&rsquo;&eacute;t&eacute; sans m&ecirc;me voyager ! En effet, rien de mieux que de ressentir l&rsquo;ambiance du voyage dans votre propre maison, gr&acirc;ce &agrave; quelques am&eacute;liorations niveau d&eacute;coration. Continuez votre lecture pour d&eacute;couvrir 5 accessoires incontournables pour cr&eacute;er votre espace d&eacute;tente, au jardin comme &agrave; l&rsquo;int&eacute;rieur de la maison, et ce, &agrave; petit prix.\n<\/div>\n","protected":false},"author":1,"featured_media":659461,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85792],"tags":[54824,54802,54804],"class_list":["post-286343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-questions-reponses","tag-decoration-zen","tag-tendances-deco","tag-inspiration-deco-ete"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment cr\u00e9er une ambiance zen ? - D\u00e9cors V\u00e9ronneau<\/title>\n<meta name=\"description\" content=\"Envie de d\u00e9crocher dans un lieu reposant ? Voici 5 accessoires incontournables pour cr\u00e9er un espace d\u00e9tente, au jardin et \u00e0 l\u2019int\u00e9rieur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment cr\u00e9er une ambiance zen ? - D\u00e9cors V\u00e9ronneau\" \/>\n<meta property=\"og:description\" content=\"Envie de d\u00e9crocher dans un lieu reposant ? Voici 5 accessoires incontournables pour cr\u00e9er un espace d\u00e9tente, au jardin et \u00e0 l\u2019int\u00e9rieur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/\" \/>\n<meta property=\"og:site_name\" content=\"D\u00e9cors V\u00e9ronneau\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/decorsveronneau\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-03T18:13:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-09T16:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2021\/05\/coin-foyer-boules-buis.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"D\u00e9cors Veronneau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"D\u00e9cors Veronneau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/\"},\"author\":{\"name\":\"D\u00e9cors Veronneau\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/person\\\/26ca3dbd5ace159014bc2c73a5d8374f\"},\"headline\":\"Comment cr\u00e9er une ambiance zen, \u00e0 l&rsquo;int\u00e9rieur comme \u00e0 l&rsquo;ext\u00e9rieur ?\",\"datePublished\":\"2021-05-03T18:13:32+00:00\",\"dateModified\":\"2023-05-09T16:25:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/\"},\"wordCount\":611,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/coin-foyer-boules-buis.png\",\"keywords\":[\"Astuces D\u00e9coration Zen\",\"Derni\u00e8res Tendances D\u00e9co\",\"Inspiration D\u00e9co \u00c9t\u00e9\"],\"articleSection\":[\"Questions et R\u00e9ponses\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/\",\"name\":\"Comment cr\u00e9er une ambiance zen ? - D\u00e9cors V\u00e9ronneau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/coin-foyer-boules-buis.png\",\"datePublished\":\"2021-05-03T18:13:32+00:00\",\"dateModified\":\"2023-05-09T16:25:01+00:00\",\"description\":\"Envie de d\u00e9crocher dans un lieu reposant ? Voici 5 accessoires incontournables pour cr\u00e9er un espace d\u00e9tente, au jardin et \u00e0 l\u2019int\u00e9rieur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/coin-foyer-boules-buis.png\",\"contentUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/coin-foyer-boules-buis.png\",\"width\":1100,\"height\":700,\"caption\":\"Coin foyer avec boules de buis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/questions-reponses\\\/comment-creer-une-ambiance-zen-interieur-exterieur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment cr\u00e9er une ambiance zen, \u00e0 l&rsquo;int\u00e9rieur comme \u00e0 l&rsquo;ext\u00e9rieur ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/\",\"name\":\"D\u00e9cors V\u00e9ronneau\",\"description\":\"Magasin de d\u00e9coration int\u00e9rieure - Plantes et fleurs artificielles\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#organization\"},\"alternateName\":\"D\u00e9cors V\u00e9ronneau\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#organization\",\"name\":\"D\u00e9cors V\u00e9ronneau\",\"alternateName\":\"D\u00e9cors V\u00e9ronneau\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-veronneau.png\",\"contentUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-veronneau.png\",\"width\":1200,\"height\":675,\"caption\":\"D\u00e9cors V\u00e9ronneau\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/decorsveronneau\",\"https:\\\/\\\/www.instagram.com\\\/decorsveronneau\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@decorsveronneau\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/person\\\/26ca3dbd5ace159014bc2c73a5d8374f\",\"name\":\"D\u00e9cors Veronneau\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment cr\u00e9er une ambiance zen ? - D\u00e9cors V\u00e9ronneau","description":"Envie de d\u00e9crocher dans un lieu reposant ? Voici 5 accessoires incontournables pour cr\u00e9er un espace d\u00e9tente, au jardin et \u00e0 l\u2019int\u00e9rieur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment cr\u00e9er une ambiance zen ? - D\u00e9cors V\u00e9ronneau","og_description":"Envie de d\u00e9crocher dans un lieu reposant ? Voici 5 accessoires incontournables pour cr\u00e9er un espace d\u00e9tente, au jardin et \u00e0 l\u2019int\u00e9rieur.","og_url":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/","og_site_name":"D\u00e9cors V\u00e9ronneau","article_publisher":"https:\/\/www.facebook.com\/decorsveronneau","article_published_time":"2021-05-03T18:13:32+00:00","article_modified_time":"2023-05-09T16:25:01+00:00","og_image":[{"width":1100,"height":700,"url":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2021\/05\/coin-foyer-boules-buis.png","type":"image\/png"}],"author":"D\u00e9cors Veronneau","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"D\u00e9cors Veronneau","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/#article","isPartOf":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/"},"author":{"name":"D\u00e9cors Veronneau","@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/person\/26ca3dbd5ace159014bc2c73a5d8374f"},"headline":"Comment cr\u00e9er une ambiance zen, \u00e0 l&rsquo;int\u00e9rieur comme \u00e0 l&rsquo;ext\u00e9rieur ?","datePublished":"2021-05-03T18:13:32+00:00","dateModified":"2023-05-09T16:25:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/"},"wordCount":611,"commentCount":0,"publisher":{"@id":"https:\/\/www.veronneau.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2021\/05\/coin-foyer-boules-buis.png","keywords":["Astuces D\u00e9coration Zen","Derni\u00e8res Tendances D\u00e9co","Inspiration D\u00e9co \u00c9t\u00e9"],"articleSection":["Questions et R\u00e9ponses"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/","url":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/","name":"Comment cr\u00e9er une ambiance zen ? - D\u00e9cors V\u00e9ronneau","isPartOf":{"@id":"https:\/\/www.veronneau.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/#primaryimage"},"image":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2021\/05\/coin-foyer-boules-buis.png","datePublished":"2021-05-03T18:13:32+00:00","dateModified":"2023-05-09T16:25:01+00:00","description":"Envie de d\u00e9crocher dans un lieu reposant ? Voici 5 accessoires incontournables pour cr\u00e9er un espace d\u00e9tente, au jardin et \u00e0 l\u2019int\u00e9rieur.","breadcrumb":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/#primaryimage","url":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2021\/05\/coin-foyer-boules-buis.png","contentUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2021\/05\/coin-foyer-boules-buis.png","width":1100,"height":700,"caption":"Coin foyer avec boules de buis"},{"@type":"BreadcrumbList","@id":"https:\/\/www.veronneau.com\/fr\/blogue\/questions-reponses\/comment-creer-une-ambiance-zen-interieur-exterieur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.veronneau.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment cr\u00e9er une ambiance zen, \u00e0 l&rsquo;int\u00e9rieur comme \u00e0 l&rsquo;ext\u00e9rieur ?"}]},{"@type":"WebSite","@id":"https:\/\/www.veronneau.com\/fr\/#website","url":"https:\/\/www.veronneau.com\/fr\/","name":"D\u00e9cors V\u00e9ronneau","description":"Magasin de d\u00e9coration int\u00e9rieure - Plantes et fleurs artificielles","publisher":{"@id":"https:\/\/www.veronneau.com\/fr\/#organization"},"alternateName":"D\u00e9cors V\u00e9ronneau","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veronneau.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.veronneau.com\/fr\/#organization","name":"D\u00e9cors V\u00e9ronneau","alternateName":"D\u00e9cors V\u00e9ronneau","url":"https:\/\/www.veronneau.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/07\/logo-veronneau.png","contentUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/07\/logo-veronneau.png","width":1200,"height":675,"caption":"D\u00e9cors V\u00e9ronneau"},"image":{"@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/decorsveronneau","https:\/\/www.instagram.com\/decorsveronneau\/","https:\/\/www.youtube.com\/@decorsveronneau"]},{"@type":"Person","@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/person\/26ca3dbd5ace159014bc2c73a5d8374f","name":"D\u00e9cors Veronneau"}]}},"_links":{"self":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts\/286343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/comments?post=286343"}],"version-history":[{"count":5,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts\/286343\/revisions"}],"predecessor-version":[{"id":659483,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts\/286343\/revisions\/659483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/media\/659461"}],"wp:attachment":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/media?parent=286343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/categories?post=286343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/tags?post=286343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}