{"id":830117,"date":"2023-11-22T12:02:55","date_gmt":"2023-11-22T17:02:55","guid":{"rendered":"https:\/\/www.veronneau.com\/?p=830117"},"modified":"2023-11-22T14:09:37","modified_gmt":"2023-11-22T19:09:37","slug":"nouvelle-tendance-pot-sapin-de-noel","status":"publish","type":"post","link":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/","title":{"rendered":"Un cache-pot comme jupe de sapin de No\u00ebl? D\u00e9couvrez la nouvelle tendance!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"830117\" class=\"elementor elementor-830117\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bfe013a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bfe013a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2f7b99\" data-id=\"b2f7b99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c065bfe elementor-widget elementor-widget-text-editor\" data-id=\"c065bfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c0 l&rsquo;approche des F\u00eates, les traditions sont sans cesse r\u00e9imagin\u00e9es et red\u00e9finies. Une tendance qui a gagn\u00e9 en popularit\u00e9 ces derni\u00e8res ann\u00e9es est certainement l&rsquo;utilisation de bases de sapin de No\u00ebl non conventionnels! Allant au-del\u00e0 des jupes de sapin classiques, les amateurs de d\u00e9coration trouvent de nouveaux moyens cr\u00e9atifs d&rsquo;\u00e9lever leur d\u00e9cor! Dans cet article, nous explorerons la nouvelle tendance des cache-pots, afin d&rsquo;ajouter une touche unique et moderne aux sapins de No\u00ebl.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cb0741 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cb0741\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e74b5b4\" data-id=\"e74b5b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf3f280 elementor-widget elementor-widget-spacer\" data-id=\"bf3f280\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e73a980 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e73a980\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-139b309\" data-id=\"139b309\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-889a3f2 elementor-widget elementor-widget-heading\" data-id=\"889a3f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Adopter la beaut\u00e9 du cache-pot<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4164607 elementor-widget elementor-widget-text-editor\" data-id=\"4164607\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La beaut\u00e9 du cache-pot r\u00e9side dans sa capacit\u00e9 \u00e0 transformer l&rsquo;ordinaire en un r\u00e9sultat unique et spectaculaire. De plus, les <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/pots-et-vases\/pots-interieurs\/grands-cache-pots\/\">cache-pots<\/a><\/span> se d\u00e9clinent en une myriade de styles adapt\u00e9s \u00e0 tous les go\u00fbts. Des paniers en osier aux pots modernes, les options sont infinies! Il est donc possible d&rsquo;obtenir un r\u00e9sultat visuellement attrayant et original qui refl\u00e8tera chaque personnalit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-384db34 elementor-widget elementor-widget-image\" data-id=\"384db34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"526\" height=\"789\" src=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/sapin-noel-cache-pot.png\" class=\"attachment-large size-large wp-image-830123\" alt=\"Sapin de No\u00ebl dans un pot noir - D\u00e9cors V\u00e9ronneau\" srcset=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/sapin-noel-cache-pot.png 526w, https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/sapin-noel-cache-pot-300x450.png 300w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Cr\u00e9dit photo: D\u00e9cors V\u00e9ronneau<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd54df4 elementor-widget elementor-widget-spacer\" data-id=\"fd54df4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aaeec8a elementor-widget elementor-widget-heading\" data-id=\"aaeec8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Magasiner ces id\u00e9es de cache-pots:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efc6e71 elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"efc6e71\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;4&quot;,&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.veronneau.com\/fr\/produits\/pots-et-vases\/pots-interieurs\/grands-cache-pots\/pot-blanc-exterieur-fini-poreux\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"POT-BLANC-EXTERIEUR-FINI-POREUX-531000046G.jpg\" style=\"background-image: url(&#039;https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/09\/POT-BLANC-EXTERIEUR-FINI-POREUX-531000046G.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.veronneau.com\/fr\/produits\/pots-et-vases\/pots-interieurs\/grands-cache-pots\/cache-pot-rond-en-fibre-dargile-anthracite\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"CACHE-POT-ROND-EN-FIBRE-DARGILE-ANTHRACITE-GRAND-45829.jpg\" style=\"background-image: url(&#039;https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/09\/CACHE-POT-ROND-EN-FIBRE-DARGILE-ANTHRACITE-GRAND-45829.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.veronneau.com\/fr\/produits\/pots-et-vases\/pots-interieurs\/grands-cache-pots\/cache-pot-gris-metallique-strie\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"CACHE-POT-GRIS-METALLIQUE-STRIE-MOYEN-1137018.jpg\" style=\"background-image: url(&#039;https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/09\/CACHE-POT-GRIS-METALLIQUE-STRIE-MOYEN-1137018.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.veronneau.com\/fr\/produits\/pots-et-vases\/pots-interieurs\/grands-cache-pots\/pot-cylindrique-en-fibrociment-brun\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"POT-CYLINDRIQUE-EN-FIBROCIMENT-BRUN-TRES-GRAND-531000014MOCHA1TG.jpg\" style=\"background-image: url(&#039;https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/09\/POT-CYLINDRIQUE-EN-FIBROCIMENT-BRUN-TRES-GRAND-531000014MOCHA1TG.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.veronneau.com\/fr\/produits\/pots-et-vases\/pots-interieurs\/grands-cache-pots\/pot-rond-en-terre-cuite-beige-18-x-20\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"POT-ROND-EN-TERRE-CUITE-BEIGE-18-X-20-1094683.jpg\" style=\"background-image: url(&#039;https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/09\/POT-ROND-EN-TERRE-CUITE-BEIGE-18-X-20-1094683.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.veronneau.com\/fr\/produits\/pots-et-vases\/pots-interieurs\/grands-cache-pots\/pot-pour-plantes-en-laiton-brosse-16-x-14\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"POT-POUR-PLANTES-EN-LAITON-BROSSE-16-X-14-1111002.jpg\" style=\"background-image: url(&#039;https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/09\/POT-POUR-PLANTES-EN-LAITON-BROSSE-16-X-14-1111002.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76d6c50 elementor-widget elementor-widget-spacer\" data-id=\"76d6c50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17052d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17052d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ec8bcb\" data-id=\"9ec8bcb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed95a31 elementor-widget elementor-widget-heading\" data-id=\"ed95a31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9lever le sapin de No\u00ebl<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f02f9db elementor-widget elementor-widget-text-editor\" data-id=\"f02f9db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Termin\u00e9 le temps o\u00f9 <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/noel\/decorations-de-noel\/cache-pieds-et-jupes-de-sapin\/\">les jupes de sapin<\/a><\/span> \u00e9taient les seules options pour d\u00e9corer le pied du sapin de No\u00ebl. Aujourd&rsquo;hui, les d\u00e9corateurs d&rsquo;int\u00e9rieur optent pour une approche plus innovante en utilisant des cache-pots comme bases pour leurs sapins. Par exemple, en plantant <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/noel\/sapins-de-noel\/\">le sapin de No\u00ebl<\/a><\/span> dans un pot en b\u00e9ton, il est possible de cr\u00e9er non seulement un r\u00e9sultat visuellement attrayant, mais aussi \u00e0 faire gagner au sapin quelques centim\u00e8tres de hauteur. Ainsi, en choisissant un pot assez grand, il est possible d&rsquo;\u00e9lever le sapin, tout en cr\u00e9ant un r\u00e9sultat accrocheur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86f020d elementor-widget elementor-widget-image\" data-id=\"86f020d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"526\" height=\"789\" src=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/sapin-alpin-blanc-pot.png\" class=\"attachment-large size-large wp-image-830164\" alt=\"Sapin alpin blanc - D\u00e9cors V\u00e9ronneau\" srcset=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/sapin-alpin-blanc-pot.png 526w, https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/sapin-alpin-blanc-pot-300x450.png 300w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Cr\u00e9dit photo: Kimberly Denis en collaboration avec D\u00e9cors V\u00e9ronneau<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c880f0 elementor-widget elementor-widget-spacer\" data-id=\"2c880f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f3150bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3150bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7560ecc\" data-id=\"7560ecc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4081ce elementor-widget elementor-widget-heading\" data-id=\"f4081ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rompre avec les traditions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d88c4cb elementor-widget elementor-widget-text-editor\" data-id=\"d88c4cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&rsquo;image embl\u00e9matique de l&rsquo;arbre de No\u00ebl fi\u00e8rement d\u00e9cor\u00e9 d&rsquo;une jupe de sapin est depuis longtemps ancr\u00e9e dans la m\u00e9moire collective. Toutefois, la polyvalence des cache-pots permet d&rsquo;exp\u00e9rimenter les diff\u00e9rentes textures, les motifs, les couleurs et les mat\u00e9riaux, r\u00e9pondant aux go\u00fbts de tous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1db03b elementor-widget elementor-widget-spacer\" data-id=\"f1db03b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b122483 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b122483\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-58cdde9\" data-id=\"58cdde9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a030d5f elementor-widget elementor-widget-heading\" data-id=\"a030d5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9corer au-del\u00e0 des festivit\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88aa32c elementor-widget elementor-widget-text-editor\" data-id=\"88aa32c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les cache-pots pour sapin de No\u00ebl ne se limitent pas \u00e0 une tendance festive \u00e9ph\u00e9m\u00e8re ; ils ont le potentiel d&rsquo;\u00eatre utilis\u00e9s tout au long de l&rsquo;ann\u00e9e. Il est donc facile de r\u00e9utiliser le cache-pot pour diff\u00e9rentes occasions, tout en adaptant ses d\u00e9corations pour correspondre \u00e0 diverses saisons. Un pot qui accueille un sapin de No\u00ebl en d\u00e9cembre peut facilement se transformer pour accueillir <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/plantes-artificielles\/\">une belle plante<\/a><\/span> en \u00e9t\u00e9 ou un arrangement en automne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3361af4 elementor-widget elementor-widget-image\" data-id=\"3361af4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"526\" height=\"789\" src=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/boules-buis-pot-blanc.png\" class=\"attachment-large size-large wp-image-830176\" alt=\"Boule de buis dans un cache-pot blanc - D\u00e9cors V\u00e9ronneau\" srcset=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/boules-buis-pot-blanc.png 526w, https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/boules-buis-pot-blanc-300x450.png 300w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Cr\u00e9dit photo: D\u00e9cors V\u00e9ronneau<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85eef15 elementor-widget elementor-widget-spacer\" data-id=\"85eef15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31be5af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31be5af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f865641\" data-id=\"f865641\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a802aa elementor-widget elementor-widget-heading\" data-id=\"9a802aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Essayer l'approche artistique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c7b447 elementor-widget elementor-widget-text-editor\" data-id=\"5c7b447\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Au-del\u00e0 du sapin dans un cache-pied standard, certains poussent le concept plus loin en traitant l&rsquo;ensemble comme une toile d&rsquo;expression artistique. Il suffit d&rsquo;imaginer quelques sapins de No\u00ebl en pots, chacun orn\u00e9 de tiges d\u00e9coratives en cascades par exemple! Cette technique a pour effet de transformer le sapin de No\u00ebl en un v\u00e9ritable chef-d&rsquo;\u0153uvre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8c9027 elementor-widget elementor-widget-spacer\" data-id=\"f8c9027\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c8b3f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c8b3f9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef687dd\" data-id=\"ef687dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1c05fa elementor-widget elementor-widget-button\" data-id=\"d1c05fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/pots-et-vases\/pots-interieurs\/grands-cache-pots\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MAGASINER TOUS LES GRANDS CACHE-POTS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"text-align: justify;\">\n\u00c0 l&rsquo;approche des F\u00eates, les traditions sont sans cesse r\u00e9imagin\u00e9es et red\u00e9finies. Une tendance \u00e9mergente qui a gagn\u00e9 en popularit\u00e9 ces derni\u00e8res ann\u00e9es est l&rsquo;utilisation de bases de sapin de No\u00ebl non conventionnels. Allant au-del\u00e0 des jupes et des pieds de sapin traditionnels, les amateurs de d\u00e9coration trouvent de nouveaux moyens cr\u00e9atifs d&rsquo;\u00e9lever leur d\u00e9cor! Dans cet article, nous explorerons la nouvelle tendance des cache-pots comme jupes de sapin, afin d&rsquo;ajouter une touche unique et moderne \u00e0 votre d\u00e9coration de No\u00ebl.<\/div>\n","protected":false},"author":8010,"featured_media":830269,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85794],"tags":[54810,54841,54845],"class_list":["post-830117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-temps-des-fetes","tag-decorations-sapins-de-noel","tag-inspiration-deco-noel","tag-noel-couleurs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un cache-pot comme jupe de sapin de No\u00ebl? - D\u00e9cors V\u00e9ronneau<\/title>\n<meta name=\"description\" content=\"R\u00e9inventez les traditions avec la tendance consistant \u00e0 utiliser des cache-pots en guise de bases de sapin de No\u00ebl! Voir les d\u00e9tails ici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un cache-pot comme jupe de sapin de No\u00ebl? - D\u00e9cors V\u00e9ronneau\" \/>\n<meta property=\"og:description\" content=\"R\u00e9inventez les traditions avec la tendance consistant \u00e0 utiliser des cache-pots en guise de bases de sapin de No\u00ebl! Voir les d\u00e9tails ici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/\" \/>\n<meta property=\"og:site_name\" content=\"D\u00e9cors V\u00e9ronneau\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/decorsveronneau\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-22T17:02:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-22T19:09:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/christmas-tree-planter-modern.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"D\u00e9cors V\u00e9ronneau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"D\u00e9cors V\u00e9ronneau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/\"},\"author\":{\"name\":\"D\u00e9cors V\u00e9ronneau\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/person\\\/e1623888573156e388847a612b529836\"},\"headline\":\"Un cache-pot comme jupe de sapin de No\u00ebl? D\u00e9couvrez la nouvelle tendance!\",\"datePublished\":\"2023-11-22T17:02:55+00:00\",\"dateModified\":\"2023-11-22T19:09:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/\"},\"wordCount\":541,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/christmas-tree-planter-modern.png\",\"keywords\":[\"D\u00e9coration Sapin de No\u00ebl\",\"Inspiration D\u00e9co No\u00ebl\",\"Tendances Couleurs de No\u00ebl\"],\"articleSection\":[\"Temps des F\u00eates\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/\",\"name\":\"Un cache-pot comme jupe de sapin de No\u00ebl? - D\u00e9cors V\u00e9ronneau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/christmas-tree-planter-modern.png\",\"datePublished\":\"2023-11-22T17:02:55+00:00\",\"dateModified\":\"2023-11-22T19:09:37+00:00\",\"description\":\"R\u00e9inventez les traditions avec la tendance consistant \u00e0 utiliser des cache-pots en guise de bases de sapin de No\u00ebl! Voir les d\u00e9tails ici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/christmas-tree-planter-modern.png\",\"contentUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/christmas-tree-planter-modern.png\",\"width\":1100,\"height\":700,\"caption\":\"Cache-pot de sapin de No\u00ebl transitionnel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/temps-des-fetes\\\/nouvelle-tendance-pot-sapin-de-noel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un cache-pot comme jupe de sapin de No\u00ebl? D\u00e9couvrez la nouvelle tendance!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/\",\"name\":\"D\u00e9cors V\u00e9ronneau\",\"description\":\"Magasin de d\u00e9coration int\u00e9rieure - Plantes et fleurs artificielles\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#organization\"},\"alternateName\":\"D\u00e9cors V\u00e9ronneau\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#organization\",\"name\":\"D\u00e9cors V\u00e9ronneau\",\"alternateName\":\"D\u00e9cors V\u00e9ronneau\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-veronneau.png\",\"contentUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-veronneau.png\",\"width\":1200,\"height\":675,\"caption\":\"D\u00e9cors V\u00e9ronneau\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/decorsveronneau\",\"https:\\\/\\\/www.instagram.com\\\/decorsveronneau\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@decorsveronneau\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/person\\\/e1623888573156e388847a612b529836\",\"name\":\"D\u00e9cors V\u00e9ronneau\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un cache-pot comme jupe de sapin de No\u00ebl? - D\u00e9cors V\u00e9ronneau","description":"R\u00e9inventez les traditions avec la tendance consistant \u00e0 utiliser des cache-pots en guise de bases de sapin de No\u00ebl! Voir les d\u00e9tails ici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/","og_locale":"fr_FR","og_type":"article","og_title":"Un cache-pot comme jupe de sapin de No\u00ebl? - D\u00e9cors V\u00e9ronneau","og_description":"R\u00e9inventez les traditions avec la tendance consistant \u00e0 utiliser des cache-pots en guise de bases de sapin de No\u00ebl! Voir les d\u00e9tails ici.","og_url":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/","og_site_name":"D\u00e9cors V\u00e9ronneau","article_publisher":"https:\/\/www.facebook.com\/decorsveronneau","article_published_time":"2023-11-22T17:02:55+00:00","article_modified_time":"2023-11-22T19:09:37+00:00","og_image":[{"width":1100,"height":700,"url":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/christmas-tree-planter-modern.png","type":"image\/png"}],"author":"D\u00e9cors V\u00e9ronneau","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"D\u00e9cors V\u00e9ronneau","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/#article","isPartOf":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/"},"author":{"name":"D\u00e9cors V\u00e9ronneau","@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/person\/e1623888573156e388847a612b529836"},"headline":"Un cache-pot comme jupe de sapin de No\u00ebl? D\u00e9couvrez la nouvelle tendance!","datePublished":"2023-11-22T17:02:55+00:00","dateModified":"2023-11-22T19:09:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/"},"wordCount":541,"commentCount":0,"publisher":{"@id":"https:\/\/www.veronneau.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/christmas-tree-planter-modern.png","keywords":["D\u00e9coration Sapin de No\u00ebl","Inspiration D\u00e9co No\u00ebl","Tendances Couleurs de No\u00ebl"],"articleSection":["Temps des F\u00eates"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/","url":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/","name":"Un cache-pot comme jupe de sapin de No\u00ebl? - D\u00e9cors V\u00e9ronneau","isPartOf":{"@id":"https:\/\/www.veronneau.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/#primaryimage"},"image":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/christmas-tree-planter-modern.png","datePublished":"2023-11-22T17:02:55+00:00","dateModified":"2023-11-22T19:09:37+00:00","description":"R\u00e9inventez les traditions avec la tendance consistant \u00e0 utiliser des cache-pots en guise de bases de sapin de No\u00ebl! Voir les d\u00e9tails ici.","breadcrumb":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/#primaryimage","url":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/christmas-tree-planter-modern.png","contentUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/11\/christmas-tree-planter-modern.png","width":1100,"height":700,"caption":"Cache-pot de sapin de No\u00ebl transitionnel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.veronneau.com\/fr\/blogue\/temps-des-fetes\/nouvelle-tendance-pot-sapin-de-noel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.veronneau.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Un cache-pot comme jupe de sapin de No\u00ebl? D\u00e9couvrez la nouvelle tendance!"}]},{"@type":"WebSite","@id":"https:\/\/www.veronneau.com\/fr\/#website","url":"https:\/\/www.veronneau.com\/fr\/","name":"D\u00e9cors V\u00e9ronneau","description":"Magasin de d\u00e9coration int\u00e9rieure - Plantes et fleurs artificielles","publisher":{"@id":"https:\/\/www.veronneau.com\/fr\/#organization"},"alternateName":"D\u00e9cors V\u00e9ronneau","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veronneau.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.veronneau.com\/fr\/#organization","name":"D\u00e9cors V\u00e9ronneau","alternateName":"D\u00e9cors V\u00e9ronneau","url":"https:\/\/www.veronneau.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/07\/logo-veronneau.png","contentUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/07\/logo-veronneau.png","width":1200,"height":675,"caption":"D\u00e9cors V\u00e9ronneau"},"image":{"@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/decorsveronneau","https:\/\/www.instagram.com\/decorsveronneau\/","https:\/\/www.youtube.com\/@decorsveronneau"]},{"@type":"Person","@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/person\/e1623888573156e388847a612b529836","name":"D\u00e9cors V\u00e9ronneau"}]}},"_links":{"self":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts\/830117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/users\/8010"}],"replies":[{"embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/comments?post=830117"}],"version-history":[{"count":5,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts\/830117\/revisions"}],"predecessor-version":[{"id":830271,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts\/830117\/revisions\/830271"}],"wp:attachment":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/media?parent=830117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/categories?post=830117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/tags?post=830117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}