{"id":895909,"date":"2025-05-06T13:49:16","date_gmt":"2025-05-06T17:49:16","guid":{"rendered":"https:\/\/www.veronneau.com\/?p=895909"},"modified":"2025-05-06T13:56:49","modified_gmt":"2025-05-06T17:56:49","slug":"top-5-herbes-ornementales-pour-decorer-votre-balcon","status":"publish","type":"post","link":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/","title":{"rendered":"Top 5 herbes ornementales pour d\u00e9corer votre balcon"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"895909\" class=\"elementor elementor-895909\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-385345f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"385345f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e04f8f\" data-id=\"9e04f8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9c1891 elementor-widget elementor-widget-text-editor\" data-id=\"f9c1891\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En 2025, place \u00e0 la d\u00e9coration verticale, aux cache-pots styl\u00e9s et aux m\u00e9langes de gramin\u00e9es ornementales avec d\u2019autres feuillages artificiels. Si votre balcon manque de cette ambiance naturelle et a\u00e9r\u00e9e \u2014 mais que vous n\u2019avez ni le temps ni l\u2019\u00e9nergie pour entretenir de vraies plantes \u2014 les tiges d\u2019herbe artificielle d\u00e9corative pourraient bien \u00eatre la solution id\u00e9ale. Install\u00e9es dans de grands pots ou regroup\u00e9es en bouquets, ces gramin\u00e9es sans entretien ajoutent du mouvement et de la texture, m\u00eame aux plus petits espaces ext\u00e9rieurs. Voici les meilleures herbes ornementales pour transformer votre balcon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dd9b37 elementor-widget elementor-widget-spacer\" data-id=\"4dd9b37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9866ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9866ee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bde3fa6\" data-id=\"bde3fa6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8a6119 elementor-widget elementor-widget-heading\" data-id=\"e8a6119\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi choisir des gramin\u00e9es artificielles ext\u00e9rieures?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e13d57 elementor-widget elementor-widget-text-editor\" data-id=\"3e13d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les herbes artificielles \u00e0 longues tiges sont con\u00e7ues pour des arrangements en hauteur ou en pots, apportant une touche raffin\u00e9e aux espaces ext\u00e9rieurs. Contrairement au gazon synth\u00e9tique de sol, ces <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/exterieur-jardin\/plantes-et-arbustes\/herbes-et-feuillages-pour-lexterieur\/\">gramin\u00e9es d\u00e9coratives<\/a><\/span> ajoutent hauteur, mouvement et texture visuelle. Elles sont parfaites pour :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d674fa2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d674fa2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7196460\" data-id=\"7196460\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f664827 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f664827\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4650738\" data-id=\"4650738\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d030dd7 elementor-widget elementor-widget-spacer\" data-id=\"d030dd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca59e3f elementor-widget elementor-widget-text-editor\" data-id=\"ca59e3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><em>\u2713\u00a0 <\/em>Cr\u00e9er de l\u2019intimit\u00e9 entre les voisins<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6058c02 elementor-widget elementor-widget-text-editor\" data-id=\"6058c02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><em>\u2713\u00a0 <\/em>Styliser les pots avec un look \u00e9pur\u00e9 et moderne<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0bfaf6 elementor-widget elementor-widget-text-editor\" data-id=\"f0bfaf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><em>\u2713 <\/em>Adoucir les balcons urbains en b\u00e9ton ou en m\u00e9tal<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ace5bd elementor-widget elementor-widget-text-editor\" data-id=\"4ace5bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><em>\u2713\u00a0 <\/em>R\u00e9sister gr\u00e2ce \u00e0 leur traitement UV<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ccaca8 elementor-widget elementor-widget-text-editor\" data-id=\"4ccaca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><em>\u2713\u00a0 <\/em>Apporter une ambiance naturelle sans entretien<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a0c439 elementor-widget elementor-widget-spacer\" data-id=\"5a0c439\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ea18c1 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9ea18c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/exterieur-jardin\/plantes-et-arbustes\/herbes-et-feuillages-pour-lexterieur\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VOIR LES OPTIONS D'HERBES<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2fb462e\" data-id=\"2fb462e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95c6fca elementor-widget elementor-widget-image\" data-id=\"95c6fca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/nc\/catalog\/Extra\/101003943-extra2.jpg\" class=\"attachment-large size-large wp-image-737817\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e39a6fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e39a6fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bcb34f8\" data-id=\"bcb34f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ceb740 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6ceb740\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12bdb43 elementor-widget elementor-widget-heading\" data-id=\"12bdb43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Astuces d\u00e9co cr\u00e9er du relief et du style<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20f3e80 elementor-widget elementor-widget-text-editor\" data-id=\"20f3e80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Voici quelques astuces d\u00e9co pour styliser les herbes vertes comme un pro :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-54f62c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54f62c5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cdb77a0\" data-id=\"cdb77a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fe65f8 elementor-widget elementor-widget-image\" data-id=\"1fe65f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"526\" height=\"789\" src=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2019\/05\/herbes-riviere-artificielles.png\" class=\"attachment-large size-large wp-image-663932\" alt=\"Herbes de rivi\u00e8re avec chaise adirondack noire - D\u00e9cors V\u00e9ronneau\" srcset=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2019\/05\/herbes-riviere-artificielles.png.webp 526w, https:\/\/www.veronneau.com\/wp-content\/uploads\/2019\/05\/herbes-riviere-artificielles-213x320.png.webp 213w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8eda00f\" data-id=\"8eda00f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7d0d6a elementor-widget elementor-widget-heading\" data-id=\"d7d0d6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. Utiliser de grands cache-pots pour cr\u00e9er de la hauteur<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45fffb0 elementor-widget elementor-widget-text-editor\" data-id=\"45fffb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Optez pour <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/pots-et-vases\/pots-exterieurs\/\">un pot moderne au fini mat ou effet pierre<\/a><\/span> et remplissez-le de tiges d\u2019herbes ornementales de 40 \u00e0 60 pouces. Cela attire le regard vers le haut et structure l\u2019espace \u2014 id\u00e9al pour les balcons \u00e9troits.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-248e67a elementor-widget elementor-widget-heading\" data-id=\"248e67a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Mixer les gramin\u00e9es avec du feuillage retombant<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7e7ae5 elementor-widget elementor-widget-text-editor\" data-id=\"f7e7ae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Associez-les \u00e0 du lierre suspendu, des vignes artificielles ou des <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/exterieur-jardin\/plantes-et-arbustes\/herbes-et-feuillages-pour-lexterieur\/\">foug\u00e8res tombantes<\/a><\/span> pour un effet jardin luxuriant. Cela apporte du volume et casse les lignes trop rigides.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9707039 elementor-widget elementor-widget-heading\" data-id=\"9707039\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. Cr\u00e9er un \u00e9cran d\u2019intimit\u00e9 verdoyant<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2377fb elementor-widget elementor-widget-text-editor\" data-id=\"f2377fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Disposez deux grands pots d\u2019herbes de chaque c\u00f4t\u00e9 de ton coin d\u00e9tente pour former un \u00e9cran v\u00e9g\u00e9tal discret. Parfait pour les balcons expos\u00e9s aux regards.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb3946e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb3946e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56668df\" data-id=\"56668df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b30e7e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7b30e7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2df9de2 elementor-widget elementor-widget-heading\" data-id=\"2df9de2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Palmar\u00e8s des herbes ornementales en 2025<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86e47a5 elementor-widget elementor-widget-spacer\" data-id=\"86e47a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e71b17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e71b17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56f76fd\" data-id=\"56f76fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-013a6d2 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"013a6d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-9bd6c99 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Gramin\u00e9e herbe aux \u00e9couvillons\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.veronneau.com\/fr\/produits\/exterieur-jardin\/thematiques-jardin\/amenagement-bacs\/herbes-de-graminee-artificielle-en-pot-exterieur-41\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">1- Herbe aux \u00e9couvillons<\/div><div class=\"elementor-slide-description\">Gramin\u00e9e avec pointes cr\u00e8me. Son mouvement souple et ses teintes naturelles en font l\u2019un des mod\u00e8les les plus r\u00e9alistes. Id\u00e9ale pour les balcons expos\u00e9s au vent, o\u00f9 les gerbes bougent l\u00e9g\u00e8rement pour un effet naturel.\nParfaite pour les d\u00e9cors scandinaves ou minimalistes.\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">MAGASINER<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-2a93c53 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Herbes en pot artificielles ext\u00e9rieures\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.veronneau.com\/fr\/produits\/exterieur-jardin\/thematiques-jardin\/amenagement-bacs\/plant-dherbes-vertes-artificielles-en-pot-15-x-15\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">2- Herbe ornementale rouge<\/div><div class=\"elementor-slide-description\">Gramin\u00e9e aux tons chauds bourgogne.\nCette herbe apporte une touche color\u00e9e et moderne. Elle cr\u00e9e un contraste int\u00e9ressant avec les feuillages verts ou les pots neutres. S\u2019agence bien avec des fleurs rouges.\nId\u00e9ale pour une note contemporaine.\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">MAGASINER<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-fa89a19 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Terracotta pot, 11 x 14&quot;\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.veronneau.com\/fr\/produits\/exterieur-jardin\/thematiques-jardin\/amenagement-bacs\/herbes-de-riviere-artificielles-dexterieur-58\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">3- Herbe de rivi\u00e8re<\/div><div class=\"elementor-slide-description\">Feuillage \u00e9lanc\u00e9 aux tons de vert. Cette herbe artificielle apporte de la hauteur sans alourdir l\u2019espace. Ses teintes contrast\u00e9es imitent \u00e0 merveille les gramin\u00e9es naturelles. Le choix parfait pour structurer un balcon moderne.\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">MAGASINER<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-85a3871 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Treillis autoportants\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.veronneau.com\/fr\/produits\/exterieur-jardin\/plantes-et-arbustes\/herbes-et-feuillages-pour-lexterieur\/herbe-vert-lime-artificielle-20\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">4- Gramin\u00e9e vert lime<\/div><div class=\"elementor-slide-description\">Herbe verte avec feuilles souples. Elle apporte de la fra\u00eecheur dans les d\u00e9cors. Son contraste avec des feuillages plus fonc\u00e9s ou des tons neutres est int\u00e9ressant. Id\u00e9ale pour dynamiser un petit espace.\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">MAGASINER<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-0d887ea swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Jardini\u00e8re de g\u00e9ranium blanc artificiel DIY\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.veronneau.com\/fr\/produits\/exterieur-jardin\/thematiques-jardin\/amenagement-bacs\/tige-de-dracaena-vert-artificiel-30\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">5- Herbe de dracaena<\/div><div class=\"elementor-slide-description\">Longues feuilles pointues aux tons verts. Inspir\u00e9e du v\u00e9ritable dracaena, cette herbe propose une silhouette structur\u00e9e. Parfaite pour un style tropical dans les jardini\u00e8res ext\u00e9rieures.<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">MAGASINER<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive pr\u00e9c\u00e9dente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive suivante\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-daa149a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"daa149a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-724e328\" data-id=\"724e328\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d7a200 elementor-widget elementor-widget-spacer\" data-id=\"5d7a200\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c824267 elementor-widget elementor-widget-text-editor\" data-id=\"c824267\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En optant pour des<span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/exterieur-jardin\/plantes-et-arbustes\/herbes-et-feuillages-pour-lexterieur\/\"> tiges artificielles ext\u00e9rieures de qualit\u00e9<\/a><\/span>, r\u00e9sistantes aux UV, vous investissez dans un produit durable\u2026 sans entretien ! Ces 5 gramin\u00e9es d\u00e9coratives sont des incontournables en 2025 pour cr\u00e9er une ambiance relaxante, styl\u00e9e et verdoyante, m\u00eame sur un petit balcon en pleine ville.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2380a0d elementor-align-left elementor-widget elementor-widget-button\" data-id=\"2380a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.veronneau.com\/fr\/categorie-produit\/exterieur-jardin\/plantes-et-arbustes\/herbes-et-feuillages-pour-lexterieur\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00c9COUVRIR LES HERBES VERTES<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"text-align: justify;\">\nEn 2025, place \u00e0 la d\u00e9coration verticale, aux cache-pots styl\u00e9s et aux m\u00e9langes de gramin\u00e9es ornementales avec d\u2019autres feuillages artificiels. Si votre balcon manque de cette ambiance naturelle et a\u00e9r\u00e9e \u2014 mais que vous n\u2019avez ni le temps ni l\u2019\u00e9nergie pour entretenir de vraies plantes \u2014 les tiges d\u2019herbe artificielle d\u00e9corative pourraient bien \u00eatre la solution id\u00e9ale. Install\u00e9es dans de grands pots ou regroup\u00e9es en bouquets, ces gramin\u00e9es sans entretien ajoutent du mouvement et de la texture, m\u00eame aux plus petits espaces ext\u00e9rieurs. Voici les meilleures herbes ornementales pour transformer votre balcon.\n<\/div>\n","protected":false},"author":8010,"featured_media":895913,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85790],"tags":[54802,85808],"class_list":["post-895909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-decoration-exterieure","tag-tendances-deco","tag-intimite-au-jardin-balcon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Top 5 herbes ornementales pour d\u00e9corer votre balcon - D\u00e9cors V\u00e9ronneau<\/title>\n<meta name=\"description\" content=\"En 2025, place \u00e0 la d\u00e9coration verticale, aux cache-pots styl\u00e9s et aux m\u00e9langes de gramin\u00e9es ornementales. Voici les meilleurs choix!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 5 herbes ornementales pour d\u00e9corer votre balcon - D\u00e9cors V\u00e9ronneau\" \/>\n<meta property=\"og:description\" content=\"En 2025, place \u00e0 la d\u00e9coration verticale, aux cache-pots styl\u00e9s et aux m\u00e9langes de gramin\u00e9es ornementales. Voici les meilleurs choix!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/\" \/>\n<meta property=\"og:site_name\" content=\"D\u00e9cors V\u00e9ronneau\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/decorsveronneau\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T17:49:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T17:56:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.veronneau.com\/wp-content\/uploads\/2025\/05\/tall-outdoor-green-grass-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"D\u00e9cors V\u00e9ronneau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"D\u00e9cors V\u00e9ronneau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/\"},\"author\":{\"name\":\"D\u00e9cors V\u00e9ronneau\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/person\\\/e1623888573156e388847a612b529836\"},\"headline\":\"Top 5 herbes ornementales pour d\u00e9corer votre balcon\",\"datePublished\":\"2025-05-06T17:49:16+00:00\",\"dateModified\":\"2025-05-06T17:56:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/\"},\"wordCount\":637,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/tall-outdoor-green-grass-2.jpg\",\"keywords\":[\"Derni\u00e8res Tendances D\u00e9co\",\"Intimit\u00e9 au Jardin Balcon\"],\"articleSection\":[\"D\u00e9coration Ext\u00e9rieure\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/\",\"name\":\"Top 5 herbes ornementales pour d\u00e9corer votre balcon - D\u00e9cors V\u00e9ronneau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/tall-outdoor-green-grass-2.jpg\",\"datePublished\":\"2025-05-06T17:49:16+00:00\",\"dateModified\":\"2025-05-06T17:56:49+00:00\",\"description\":\"En 2025, place \u00e0 la d\u00e9coration verticale, aux cache-pots styl\u00e9s et aux m\u00e9langes de gramin\u00e9es ornementales. Voici les meilleurs choix!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/tall-outdoor-green-grass-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/tall-outdoor-green-grass-2.jpg\",\"width\":1100,\"height\":700,\"caption\":\"Herbe de rivi\u00e8re artificielle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/blogue\\\/decoration-exterieure\\\/top-5-herbes-ornementales-pour-decorer-votre-balcon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 5 herbes ornementales pour d\u00e9corer votre balcon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/\",\"name\":\"D\u00e9cors V\u00e9ronneau\",\"description\":\"Magasin de d\u00e9coration int\u00e9rieure - Plantes et fleurs artificielles\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#organization\"},\"alternateName\":\"D\u00e9cors V\u00e9ronneau\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#organization\",\"name\":\"D\u00e9cors V\u00e9ronneau\",\"alternateName\":\"D\u00e9cors V\u00e9ronneau\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-veronneau.png\",\"contentUrl\":\"https:\\\/\\\/www.veronneau.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-veronneau.png\",\"width\":1200,\"height\":675,\"caption\":\"D\u00e9cors V\u00e9ronneau\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/decorsveronneau\",\"https:\\\/\\\/www.instagram.com\\\/decorsveronneau\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@decorsveronneau\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.veronneau.com\\\/fr\\\/#\\\/schema\\\/person\\\/e1623888573156e388847a612b529836\",\"name\":\"D\u00e9cors V\u00e9ronneau\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Top 5 herbes ornementales pour d\u00e9corer votre balcon - D\u00e9cors V\u00e9ronneau","description":"En 2025, place \u00e0 la d\u00e9coration verticale, aux cache-pots styl\u00e9s et aux m\u00e9langes de gramin\u00e9es ornementales. Voici les meilleurs choix!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 5 herbes ornementales pour d\u00e9corer votre balcon - D\u00e9cors V\u00e9ronneau","og_description":"En 2025, place \u00e0 la d\u00e9coration verticale, aux cache-pots styl\u00e9s et aux m\u00e9langes de gramin\u00e9es ornementales. Voici les meilleurs choix!","og_url":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/","og_site_name":"D\u00e9cors V\u00e9ronneau","article_publisher":"https:\/\/www.facebook.com\/decorsveronneau","article_published_time":"2025-05-06T17:49:16+00:00","article_modified_time":"2025-05-06T17:56:49+00:00","og_image":[{"width":1100,"height":700,"url":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2025\/05\/tall-outdoor-green-grass-2.jpg","type":"image\/jpeg"}],"author":"D\u00e9cors V\u00e9ronneau","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"D\u00e9cors V\u00e9ronneau","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/#article","isPartOf":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/"},"author":{"name":"D\u00e9cors V\u00e9ronneau","@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/person\/e1623888573156e388847a612b529836"},"headline":"Top 5 herbes ornementales pour d\u00e9corer votre balcon","datePublished":"2025-05-06T17:49:16+00:00","dateModified":"2025-05-06T17:56:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/"},"wordCount":637,"commentCount":0,"publisher":{"@id":"https:\/\/www.veronneau.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2025\/05\/tall-outdoor-green-grass-2.jpg","keywords":["Derni\u00e8res Tendances D\u00e9co","Intimit\u00e9 au Jardin Balcon"],"articleSection":["D\u00e9coration Ext\u00e9rieure"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/","url":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/","name":"Top 5 herbes ornementales pour d\u00e9corer votre balcon - D\u00e9cors V\u00e9ronneau","isPartOf":{"@id":"https:\/\/www.veronneau.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/#primaryimage"},"image":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2025\/05\/tall-outdoor-green-grass-2.jpg","datePublished":"2025-05-06T17:49:16+00:00","dateModified":"2025-05-06T17:56:49+00:00","description":"En 2025, place \u00e0 la d\u00e9coration verticale, aux cache-pots styl\u00e9s et aux m\u00e9langes de gramin\u00e9es ornementales. Voici les meilleurs choix!","breadcrumb":{"@id":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/#primaryimage","url":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2025\/05\/tall-outdoor-green-grass-2.jpg","contentUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2025\/05\/tall-outdoor-green-grass-2.jpg","width":1100,"height":700,"caption":"Herbe de rivi\u00e8re artificielle"},{"@type":"BreadcrumbList","@id":"https:\/\/www.veronneau.com\/fr\/blogue\/decoration-exterieure\/top-5-herbes-ornementales-pour-decorer-votre-balcon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.veronneau.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Top 5 herbes ornementales pour d\u00e9corer votre balcon"}]},{"@type":"WebSite","@id":"https:\/\/www.veronneau.com\/fr\/#website","url":"https:\/\/www.veronneau.com\/fr\/","name":"D\u00e9cors V\u00e9ronneau","description":"Magasin de d\u00e9coration int\u00e9rieure - Plantes et fleurs artificielles","publisher":{"@id":"https:\/\/www.veronneau.com\/fr\/#organization"},"alternateName":"D\u00e9cors V\u00e9ronneau","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veronneau.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.veronneau.com\/fr\/#organization","name":"D\u00e9cors V\u00e9ronneau","alternateName":"D\u00e9cors V\u00e9ronneau","url":"https:\/\/www.veronneau.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/07\/logo-veronneau.png","contentUrl":"https:\/\/www.veronneau.com\/wp-content\/uploads\/2023\/07\/logo-veronneau.png","width":1200,"height":675,"caption":"D\u00e9cors V\u00e9ronneau"},"image":{"@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/decorsveronneau","https:\/\/www.instagram.com\/decorsveronneau\/","https:\/\/www.youtube.com\/@decorsveronneau"]},{"@type":"Person","@id":"https:\/\/www.veronneau.com\/fr\/#\/schema\/person\/e1623888573156e388847a612b529836","name":"D\u00e9cors V\u00e9ronneau"}]}},"_links":{"self":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts\/895909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/users\/8010"}],"replies":[{"embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/comments?post=895909"}],"version-history":[{"count":5,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts\/895909\/revisions"}],"predecessor-version":[{"id":895969,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/posts\/895909\/revisions\/895969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/media\/895913"}],"wp:attachment":[{"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/media?parent=895909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/categories?post=895909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.veronneau.com\/fr\/wp-json\/wp\/v2\/tags?post=895909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}